{"id":286,"count":48,"description":"","link":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/","name":"KSeF","slug":"ksef","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KSeF - Blog Asseco BS<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KSeF - Blog Asseco BS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/assecobs.pl\/blog\/tag\/ksef\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Asseco BS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@asseco_bs\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/tag\\\/ksef\\\/\",\"url\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/tag\\\/ksef\\\/\",\"name\":\"KSeF - Blog Asseco BS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/tag\\\/ksef\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/tag\\\/ksef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KSeF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/\",\"name\":\"Blog Asseco BS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#organization\",\"name\":\"Asseco Business Solutions\",\"url\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/01\\\/abs-logo-user.jpg\",\"contentUrl\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/01\\\/abs-logo-user.jpg\",\"width\":250,\"height\":251,\"caption\":\"Asseco Business Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/assecobs.pl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/erpbyasseco\\\/\",\"https:\\\/\\\/x.com\\\/asseco_bs\",\"https:\\\/\\\/pl.linkedin.com\\\/company\\\/asseco-business-solutions-sa\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCU4su9i0ZMIrsS0P0bkYOA\\\/featured\",\"https:\\\/\\\/pl.wikipedia.org\\\/wiki\\\/Asseco_Business_Solutions\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KSeF - Blog Asseco BS","robots":{"index":"noindex","follow":"follow"},"og_locale":"pl_PL","og_type":"article","og_title":"KSeF - Blog Asseco BS","og_url":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/","og_site_name":"Blog Asseco BS","twitter_card":"summary_large_image","twitter_site":"@asseco_bs","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/","url":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/","name":"KSeF - Blog Asseco BS","isPartOf":{"@id":"https:\/\/assecobs.pl\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/assecobs.pl\/blog\/tag\/ksef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/assecobs.pl\/blog\/"},{"@type":"ListItem","position":2,"name":"KSeF"}]},{"@type":"WebSite","@id":"https:\/\/assecobs.pl\/blog\/#website","url":"https:\/\/assecobs.pl\/blog\/","name":"Blog Asseco BS","description":"","publisher":{"@id":"https:\/\/assecobs.pl\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/assecobs.pl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/assecobs.pl\/blog\/#organization","name":"Asseco Business Solutions","url":"https:\/\/assecobs.pl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/assecobs.pl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assecobs.pl\/blog\/wp-content\/uploads\/sites\/14\/2020\/01\/abs-logo-user.jpg","contentUrl":"https:\/\/assecobs.pl\/blog\/wp-content\/uploads\/sites\/14\/2020\/01\/abs-logo-user.jpg","width":250,"height":251,"caption":"Asseco Business Solutions"},"image":{"@id":"https:\/\/assecobs.pl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/erpbyasseco\/","https:\/\/x.com\/asseco_bs","https:\/\/pl.linkedin.com\/company\/asseco-business-solutions-sa","https:\/\/www.youtube.com\/channel\/UCCU4su9i0ZMIrsS0P0bkYOA\/featured","https:\/\/pl.wikipedia.org\/wiki\/Asseco_Business_Solutions"]}]}},"_links":{"self":[{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/tags\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/posts?tags=286"},{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/komunikaty?tags=286"},{"href":"https:\/\/assecobs.pl\/blog\/wp-json\/wp\/v2\/media?tags=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}